{"id":2779,"date":"2020-05-18T16:04:20","date_gmt":"2020-05-18T16:04:20","guid":{"rendered":"https:\/\/perpetualcharity.com\/?p=2779"},"modified":"2020-05-19T22:06:11","modified_gmt":"2020-05-19T22:06:11","slug":"wango","status":"publish","type":"post","link":"https:\/\/perpetualcharity.com\/de\/wango\/","title":{"rendered":"Wango"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2779\" class=\"elementor elementor-2779\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4454f012 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4454f012\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7219a55a\" data-id=\"7219a55a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2917ef77 elementor-widget elementor-widget-text-editor\" data-id=\"2917ef77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- wp:paragraph -->\n<p>Die World Association of Non-Governmental Organizations (WANGO) ist eine internationale Organisation, die NGOs weltweit in der Sache der F\u00f6rderung des Friedens und des globalen Wohlergehens vereint. WANGO tr\u00e4gt dazu bei, den NGOs den Mechanismus und die Unterst\u00fctzung zur Verf\u00fcgung zu stellen, die sie ben\u00f6tigen, um ihre Beitr\u00e4ge zur L\u00f6sung der Grundprobleme der Menschheit miteinander zu verbinden, Partnerschaften einzugehen, zu teilen, zu inspirieren und zu vermehren.<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e82d9d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e82d9d6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdff603\" data-id=\"fdff603\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62537d0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"62537d0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.wango.org\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Besuchen Sie ihre Website<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die World Association of Non-Governmental Organizations (WANGO) ist eine internationale Organisation, die NGOs auf der ganzen Welt vereint, um Frieden und globales Wohlergehen zu f\u00f6rdern. WANGO hilft dabei, den Mechanismus und die Unterst\u00fctzung bereitzustellen, die NGOs ben\u00f6tigen, um sich zu vernetzen, Partnerschaften einzugehen, sich auszutauschen, zu inspirieren und ihre Beitr\u00e4ge zur L\u00f6sung der grundlegenden Probleme der Menschheit zu vervielfachen. Besuchen Sie ihre Website<\/p>","protected":false},"author":1,"featured_media":3102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wds_primary_category":0},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/posts\/2779"}],"collection":[{"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/comments?post=2779"}],"version-history":[{"count":0,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/posts\/2779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/media\/3102"}],"wp:attachment":[{"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/media?parent=2779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/categories?post=2779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perpetualcharity.com\/de\/wp-json\/wp\/v2\/tags?post=2779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}